{"id":108,"count":3,"description":"","link":"https:\/\/agradocosmetic.com\/en\/categoria-de-producto\/adulto\/","name":"Adult","slug":"adulto","taxonomy":"categoria-de-producto","parent":107,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adulto - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/en\/categoria-de-producto\/adulto\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adulto - Agrado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/en\/categoria-de-producto\/adulto\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/adulto\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/adulto\\\/\",\"name\":\"Adulto - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/adulto\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/adulto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado Bucal\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/cuidado-bucal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adulto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adulto - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/en\/categoria-de-producto\/adulto\/","og_locale":"en_GB","og_type":"article","og_title":"Adulto - Agrado","og_url":"https:\/\/agradocosmetic.com\/en\/categoria-de-producto\/adulto\/","og_site_name":"Agrado","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/adulto\/","url":"https:\/\/agradocosmetic.com\/categoria-de-producto\/adulto\/","name":"Adulto - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/adulto\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/adulto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Cuidado Bucal","item":"https:\/\/agradocosmetic.com\/categoria-de-producto\/cuidado-bucal\/"},{"@type":"ListItem","position":3,"name":"Adulto"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Liking","description":"cosmetic","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Liking","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/en\/wp-json\/wp\/v2\/categoria-de-producto\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/en\/wp-json\/wp\/v2\/categoria-de-producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/en\/wp-json\/wp\/v2\/taxonomies\/categoria-de-producto"}],"up":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/en\/wp-json\/wp\/v2\/categoria-de-producto\/107"}],"wp:post_type":[{"href":"https:\/\/agradocosmetic.com\/en\/wp-json\/wp\/v2\/producto?categoria-de-producto=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}