{"id":25096,"date":"2024-04-03T07:15:48","date_gmt":"2024-04-03T07:15:48","guid":{"rendered":"https:\/\/agradocosmetic.com\/?post_type=producto&#038;p=25096"},"modified":"2026-07-06T14:52:00","modified_gmt":"2026-07-06T13:52:00","slug":"crema-protectora-facial-spf50","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/it\/producto\/crema-protectora-facial-spf50\/","title":{"rendered":"Crema Protettiva Viso SPF50+"},"content":{"rendered":"<p>Crema viso protezione antimacchia e antiet\u00e0 con protezione molto alta SPF50+. Con azione antiossidante, protegge la pelle dai raggi UV, UVA, infrarossi e dalla luce blu. Illumina la pelle e riduce le rughe visibili. Ideale per viso e d\u00e9collet\u00e9. Texture liquida e assorbimento immediato. Resistente all'acqua.<\/p>","protected":false},"featured_media":35901,"template":"","categoria-de-producto":[95,637,98,96,722],"class_list":["post-25096","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-proteccion-solar","categoria-de-producto-50-spf-proteccion-solar","categoria-de-producto-formatos-viaje","categoria-de-producto-proteccion-facial","categoria-de-producto-crema-facial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crema Protectora Facial SPF50+ - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/it\/producto\/crema-protectora-facial-spf50\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crema Protectora Facial SPF50+ - Agrado\" \/>\n<meta property=\"og:description\" content=\"Crema facial protectora antimanchas y antiedad con protecci\u00f3n muy alta SPF50+. Con acci\u00f3n antioxidante, protege la piel de los rayos UV, UVA, infrarrojos y luz azul. Ilumina la piel y reduce las arrugas visibles. Ideal para cara y escote. Con textura fluida y absorci\u00f3n inmediata. Resistente al agua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/it\/producto\/crema-protectora-facial-spf50\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T13:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2024\/04\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/\",\"name\":\"Crema Protectora Facial SPF50+ - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp\",\"datePublished\":\"2024-04-03T07:15:48+00:00\",\"dateModified\":\"2026-07-06T13:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-protectora-facial-spf50\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crema Protectora Facial SPF50+\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crema protettiva per il viso SPF50+ - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/it\/producto\/crema-protectora-facial-spf50\/","og_locale":"it_IT","og_type":"article","og_title":"Crema Protectora Facial SPF50+ - Agrado","og_description":"Crema facial protectora antimanchas y antiedad con protecci\u00f3n muy alta SPF50+. Con acci\u00f3n antioxidante, protege la piel de los rayos UV, UVA, infrarrojos y luz azul. Ilumina la piel y reduce las arrugas visibles. Ideal para cara y escote. Con textura fluida y absorci\u00f3n inmediata. Resistente al agua.","og_url":"https:\/\/agradocosmetic.com\/it\/producto\/crema-protectora-facial-spf50\/","og_site_name":"Agrado","article_modified_time":"2026-07-06T13:52:00+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2024\/04\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/","url":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/","name":"Crema protettiva per il viso SPF50+ - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2024\/04\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp","datePublished":"2024-04-03T07:15:48+00:00","dateModified":"2026-07-06T13:52:00+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2024\/04\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2024\/04\/Agrado-Sun-Care-Cream-Facial-50-spf_1.webp","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/crema-protectora-facial-spf50\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Crema Protectora Facial SPF50+"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Mi piace","description":"cosmetico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Mi piace","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/producto\/25096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/media\/35901"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/media?parent=25096"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/categoria-de-producto?post=25096"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}