{"id":30138,"date":"2025-05-12T17:00:57","date_gmt":"2025-05-12T16:00:57","guid":{"rendered":"https:\/\/agradocosmetic.com\/?post_type=producto&#038;p=30138"},"modified":"2026-03-04T10:01:34","modified_gmt":"2026-03-04T09:01:34","slug":"desodorante-antitranspirante-dry-control-unisex","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/it\/producto\/desodorante-antitranspirante-dry-control-unisex\/","title":{"rendered":"Deodorante Antitraspirante Dry Control"},"content":{"rendered":"<p class=\"translation-block\">CO2 compensato<br>\nAsciutto al tatto <br>\n0% alcol. <br>\n72 ore di protezione.<br>\nProfumo neutro unisex che mantiene la freschezza tutto il giorno.<\/p>","protected":false},"featured_media":30139,"template":"","categoria-de-producto":[81,89,90],"class_list":["post-30138","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-cuidado-corporal","categoria-de-producto-desodorante","categoria-de-producto-spray"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desodorante Antitranspirante Dry Control - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/it\/producto\/desodorante-antitranspirante-dry-control-unisex\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desodorante Antitranspirante Dry Control - Agrado\" \/>\n<meta property=\"og:description\" content=\"CO2 compensado Tacto seco. 0% alcohol. 72 horas de protecci\u00f3n. Perfume neutro unisex que mantiene la frescura durante todo el d\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/it\/producto\/desodorante-antitranspirante-dry-control-unisex\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T09:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/05\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/\",\"name\":\"Desodorante Antitranspirante Dry Control - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp\",\"datePublished\":\"2025-05-12T16:00:57+00:00\",\"dateModified\":\"2026-03-04T09:01:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/desodorante-antitranspirante-dry-control-unisex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desodorante Antitranspirante Dry Control\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deodorante antitraspirante Dry Control - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/it\/producto\/desodorante-antitranspirante-dry-control-unisex\/","og_locale":"it_IT","og_type":"article","og_title":"Desodorante Antitranspirante Dry Control - Agrado","og_description":"CO2 compensado Tacto seco. 0% alcohol. 72 horas de protecci\u00f3n. Perfume neutro unisex que mantiene la frescura durante todo el d\u00eda.","og_url":"https:\/\/agradocosmetic.com\/it\/producto\/desodorante-antitranspirante-dry-control-unisex\/","og_site_name":"Agrado","article_modified_time":"2026-03-04T09:01:34+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/05\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/","url":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/","name":"Deodorante antitraspirante Dry Control - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/05\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp","datePublished":"2025-05-12T16:00:57+00:00","dateModified":"2026-03-04T09:01:34+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/05\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/05\/30009715-AGRADO-DESOD-ANTIT-AER-DRY-CONTROL-200ML.webp","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/desodorante-antitranspirante-dry-control-unisex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Desodorante Antitranspirante Dry Control"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Mi piace","description":"cosmetico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Mi piace","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/producto\/30138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/media\/30139"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/media?parent=30138"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/it\/wp-json\/wp\/v2\/categoria-de-producto?post=30138"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}