{"id":926,"count":2,"description":"","link":"https:\/\/agradocosmetic.com\/pt\/categoria-de-producto\/contorno-ojos\/","name":"Contorno dos olhos","slug":"contorno-ojos","taxonomy":"categoria-de-producto","parent":919,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contorno de ojos - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/categoria-de-producto\/contorno-ojos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contorno de ojos - Agrado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/categoria-de-producto\/contorno-ojos\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/contorno-ojos\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/contorno-ojos\\\/\",\"name\":\"Contorno de ojos - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/contorno-ojos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/contorno-ojos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado Facial\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/cuidado-facial\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tratamiento Facial\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/categoria-de-producto\\\/tratamiento-facial\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Contorno de ojos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contorno de ojos - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/categoria-de-producto\/contorno-ojos\/","og_locale":"pt_PT","og_type":"article","og_title":"Contorno de ojos - Agrado","og_url":"https:\/\/agradocosmetic.com\/pt\/categoria-de-producto\/contorno-ojos\/","og_site_name":"Agrado","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/contorno-ojos\/","url":"https:\/\/agradocosmetic.com\/categoria-de-producto\/contorno-ojos\/","name":"Contorno dos olhos - Agrad\u00e1vel","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/contorno-ojos\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/categoria-de-producto\/contorno-ojos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Cuidado Facial","item":"https:\/\/agradocosmetic.com\/categoria-de-producto\/cuidado-facial\/"},{"@type":"ListItem","position":3,"name":"Tratamiento Facial","item":"https:\/\/agradocosmetic.com\/categoria-de-producto\/tratamiento-facial\/"},{"@type":"ListItem","position":4,"name":"Contorno de ojos"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto\/926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/taxonomies\/categoria-de-producto"}],"up":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto\/919"}],"wp:post_type":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto?categoria-de-producto=926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}