{"id":19141,"date":"2021-11-18T18:33:18","date_gmt":"2021-11-18T17:33:18","guid":{"rendered":"https:\/\/www.agradocosmetic.com\/?p=19141"},"modified":"2023-11-18T16:58:51","modified_gmt":"2023-11-18T16:58:51","slug":"home-spa-ritual-cuidado-corporal","status":"publish","type":"post","link":"https:\/\/agradocosmetic.com\/pt\/home-spa-ritual-cuidado-corporal\/","title":{"rendered":"Home Spa, ritual de cuidado corporal"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O ritual de beleza definitivo chega na AGRADO Cosmetic! N\u00f3s apresentamos voc\u00ea <strong><a href=\"https:\/\/agradocosmetic.com\/pt\/?s=HOME+SPA\" target=\"_blank\" rel=\"noreferrer noopener\">Spa dom\u00e9stico<\/a>, <\/strong>ritual de cuidados com o corpo,<strong> a nova edi\u00e7\u00e3o limitada pensada para lhe proporcionar momentos de grande relaxamento, mimos e cuidados com a sua pele<\/strong>. Continue lendo e deixe-se encantar pelos encantos e benef\u00edcios desta nova linha. Voc\u00ea merece!<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/agradocosmetic.com\/pt\/?s=HOME+SPA\" target=\"_blank\" rel=\"noreferrer noopener\">Spa dom\u00e9stico<\/a>, ritual de cuidado corporal, \u00e9 um<strong> apelo \u00e0 fuga e ao relaxamento ap\u00f3s um dia intenso e agitado de rotina<\/strong>. Estes produtos convidam-no a desligar-se, a reservar um tempo para si e a recuperar o equil\u00edbrio entre corpo e mente. Al\u00e9m do mais, <strong>Proporciona um grande n\u00famero de benef\u00edcios a n\u00edvel f\u00edsico, como hidratar e renovar a pele.<\/strong>, ent\u00e3o a sensa\u00e7\u00e3o de conforto ser\u00e1 mais que completa.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Assim, a nova linha <a href=\"https:\/\/agradocosmetic.com\/pt\/?s=HOME+SPA\" target=\"_blank\" rel=\"noreferrer noopener\">Spa dom\u00e9stico<\/a>, ritual de cuidado corporal, oferece tudo o que voc\u00ea precisa para fazer seu pr\u00f3prio tratamento de cuidado e relaxamento em casa. \u00c9 composto por <strong>dois pacotes de produtos exclusivos<\/strong>: a tradi\u00e7\u00e3o do Jap\u00e3o e do Mediterr\u00e2neo. Cada um deles inclui uma Esfolia\u00e7\u00e3o Corporal, uma Mousse Hidratante e um Gel de Banho e Duche; criado com f\u00f3rmulas e texturas sofisticadas que ir\u00e3o envolv\u00ea-lo e proporcionar-lhe uma experi\u00eancia \u00fanica. Al\u00e9m disso, todos os produtos possuem o selo <strong>Adequado para veganos<\/strong>.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Home Spa Cuidados Japoneses<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/agradocosmetic.com\/pt\/producto\/home-spa-japanese-care\/\" target=\"_blank\" rel=\"noreferrer noopener\">Home Spa Cuidados Japoneses<\/a><\/strong> by AGRADO \u00e9 inspirado na tradi\u00e7\u00e3o japonesa. Os seus produtos s\u00e3o perfumados com flor de cerejeira oriental, o que lhe proporcionar\u00e1 um momento zen \u00fanico.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Home Spa Mediterr\u00e2neo Bem<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por outro lado, <strong><a href=\"https:\/\/agradocosmetic.com\/pt\/producto\/home-spa-mediterranean-wellness\/\" target=\"_blank\" rel=\"noreferrer noopener\">Home Spa Mediterr\u00e2neo Bem-Estar<\/a><\/strong> de Agrado leva-nos ao Mediterr\u00e2neo atrav\u00e9s dos sentidos, gra\u00e7as ao seu perfume de laranja e cedro.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Escolha o seu aroma preferido e siga estes passos para desfrutar do Home Spa, um ritual de cuidado corporal em casa:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>PASSO 1. Desconecte o telefone e toque sua m\u00fasica relaxante favorita.\u00a0<\/li>\r\n<li>PASSO 2. Com a \u00e1gua do chuveiro na temperatura ideal, descubra a suavidade e a cremosidade do Gel de Banho e Duche, que limpa, cuida e deixa uma agrad\u00e1vel fragr\u00e2ncia na pele.\u00a0<\/li>\r\n<li>PASSO 3. A seguir \u00e9 hora de remover as c\u00e9lulas mortas e renovar a pele com o Esfoliante Corporal. Este produto \u00e0 base de arroz e caro\u00e7os de azeitona torna-se um passo essencial para conseguir uma pele mais firme e el\u00e1stica.\u00a0<\/li>\r\n<li>PASSO 4. Com a pele j\u00e1 seca, basta desfrutar desta textura surpreendente da Mousse Hidratante que hidrata e suaviza a pele com uma aplica\u00e7\u00e3o confort\u00e1vel e agrad\u00e1vel.\u00a0<\/li>\r\n<li>PASSO 5. Por fim, o passo mais importante: sorria e valorize o momento. Repita este ritual todos os dias que precisar e aproveite.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea j\u00e1 conhece o \u00faltimo lan\u00e7amento da AGRADO Cosmetic, monte seu pr\u00f3prio spa em casa com o Home Spa e descubra como \u00e9 f\u00e1cil se sentir bem. O presente perfeito para voc\u00ea ou para quem voc\u00ea mais ama.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Llega a AGRADO Cosmetic el ritual de belleza definitivo! Os presentamos Home Spa, ritual de cuidado corporal, la nueva edici\u00f3n limitada pensada para regalarte un rato de mucho relax, mimos y cuidados para tu piel. Sigue leyendo y d\u00e9jate embaucar por los encantos y beneficios de esta nueva l\u00ednea. \u00a1Te lo mereces! Home Spa, ritual [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":21302,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[149,1],"tags":[126,295,289,359,360,361,362,158,303,363,364],"class_list":["post-19141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporal","category-todos","tag-agrado","tag-corporal","tag-cuidado-de-la-piel","tag-exfoliante","tag-gel-de-bano","tag-home-spa","tag-mousse-hidratante","tag-piel","tag-relax","tag-ritual-de-belleza","tag-spa-en-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home Spa, ritual de cuidado corporal - Agrado Cosmetic<\/title>\n<meta name=\"description\" content=\"Home Spa, ritual de cuidado corporal, es la excusa perfecta para mimarte, cuidar tu piel y desconectar tu mente. \u00a1Desc\u00fabrelo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/home-spa-ritual-cuidado-corporal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Spa, ritual de cuidado corporal - Agrado Cosmetic\" \/>\n<meta property=\"og:description\" content=\"Home Spa, ritual de cuidado corporal, es la excusa perfecta para mimarte, cuidar tu piel y desconectar tu mente. \u00a1Desc\u00fabrelo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/home-spa-ritual-cuidado-corporal\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T17:33:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-18T16:58:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agradocosmetic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"agradocosmetic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/\"},\"author\":{\"name\":\"agradocosmetic\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/person\\\/732e8d396022e25f9340196f83d6789d\"},\"headline\":\"Home Spa, ritual de cuidado corporal\",\"datePublished\":\"2021-11-18T17:33:18+00:00\",\"dateModified\":\"2023-11-18T16:58:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/gel-spa-mousse-agrado.jpg\",\"keywords\":[\"agrado\",\"corporal\",\"cuidado de la piel\",\"exfoliante\",\"gel de ba\u00f1o\",\"home spa\",\"mousse hidratante\",\"piel\",\"relax\",\"ritual de belleza\",\"spa en casa\"],\"articleSection\":[\"Corporal\",\"Todos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/\",\"name\":\"Home Spa, ritual de cuidado corporal - Agrado Cosmetic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/gel-spa-mousse-agrado.jpg\",\"datePublished\":\"2021-11-18T17:33:18+00:00\",\"dateModified\":\"2023-11-18T16:58:51+00:00\",\"description\":\"Home Spa, ritual de cuidado corporal, es la excusa perfecta para mimarte, cuidar tu piel y desconectar tu mente. \u00a1Desc\u00fabrelo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/gel-spa-mousse-agrado.jpg\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/gel-spa-mousse-agrado.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/home-spa-ritual-cuidado-corporal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home Spa, ritual de cuidado corporal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/person\\\/732e8d396022e25f9340196f83d6789d\",\"name\":\"agradocosmetic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"caption\":\"agradocosmetic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spa em casa, ritual de cuidados corporais - Agrado Cosmetic","description":"O Home Spa, um ritual de cuidados corporais, \u00e9 a desculpa perfeita para se mimar, cuidar da pele e desconectar da mente. Descubra!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/home-spa-ritual-cuidado-corporal\/","og_locale":"pt_PT","og_type":"article","og_title":"Home Spa, ritual de cuidado corporal - Agrado Cosmetic","og_description":"Home Spa, ritual de cuidado corporal, es la excusa perfecta para mimarte, cuidar tu piel y desconectar tu mente. \u00a1Desc\u00fabrelo!","og_url":"https:\/\/agradocosmetic.com\/pt\/home-spa-ritual-cuidado-corporal\/","og_site_name":"Agrado","article_published_time":"2021-11-18T17:33:18+00:00","article_modified_time":"2023-11-18T16:58:51+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg","type":"image\/jpeg"}],"author":"agradocosmetic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"agradocosmetic","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#article","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/"},"author":{"name":"agradocosmetic","@id":"https:\/\/agradocosmetic.com\/#\/schema\/person\/732e8d396022e25f9340196f83d6789d"},"headline":"Home Spa, ritual de cuidado corporal","datePublished":"2021-11-18T17:33:18+00:00","dateModified":"2023-11-18T16:58:51+00:00","mainEntityOfPage":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"image":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg","keywords":["agrado","corporal","cuidado de la piel","exfoliante","gel de ba\u00f1o","home spa","mousse hidratante","piel","relax","ritual de belleza","spa en casa"],"articleSection":["Corporal","Todos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/","url":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/","name":"Spa em casa, ritual de cuidados corporais - Agrado Cosmetic","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg","datePublished":"2021-11-18T17:33:18+00:00","dateModified":"2023-11-18T16:58:51+00:00","description":"O Home Spa, um ritual de cuidados corporais, \u00e9 a desculpa perfeita para se mimar, cuidar da pele e desconectar da mente. Descubra!","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2021\/11\/gel-spa-mousse-agrado.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/home-spa-ritual-cuidado-corporal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Home Spa, ritual de cuidado corporal"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/agradocosmetic.com\/#\/schema\/person\/732e8d396022e25f9340196f83d6789d","name":"agradocosm\u00e9tico","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","caption":"agradocosmetic"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/19141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/comments?post=19141"}],"version-history":[{"count":1,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/19141\/revisions"}],"predecessor-version":[{"id":21303,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/19141\/revisions\/21303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/21302"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=19141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categories?post=19141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/tags?post=19141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}