{"id":20773,"date":"2023-05-08T11:58:11","date_gmt":"2023-05-08T10:58:11","guid":{"rendered":"https:\/\/www.agradocosmetic.com\/?p=20773"},"modified":"2023-11-18T16:58:46","modified_gmt":"2023-11-18T16:58:46","slug":"prepara-tu-pelo-para-el-verano-con-la-linea-keratina","status":"publish","type":"post","link":"https:\/\/agradocosmetic.com\/pt\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/","title":{"rendered":"Prepare seus cabelos para o ver\u00e3o com a Linha Queratina"},"content":{"rendered":"<p>O ver\u00e3o est\u00e1 chegando! Mais uma vez, retornam dias de calor intenso, piscina, praia e sol. E embora queiramos muito esses planos, temos que preparar o cabelo para que n\u00e3o sofra muito. Se voc\u00ea ainda n\u00e3o sabe como, n\u00e3o entre em p\u00e2nico, pois em <a href=\"https:\/\/agradocosmetic.com\/pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agrado Cosm\u00e9ticos<\/a> Mostramos-lhe a melhor solu\u00e7\u00e3o: <a href=\"https:\/\/agradocosmetic.com\/pt\/linea\/keratina\/\" target=\"_blank\" rel=\"noreferrer noopener\">A Linha Queratina<\/a>.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">O que \u00e9 queratina?<\/h2>\r\n\r\n\r\n\r\n<p>Certamente voc\u00ea j\u00e1 ouviu falar disso mil vezes e isso n\u00e3o nos surpreende! A queratina oferece-nos m\u00faltiplos benef\u00edcios, tanto no tratamento espec\u00edfico como no uso di\u00e1rio. \u00c9 a dica infal\u00edvel para muitos cabelos!<\/p>\r\n\r\n\r\n\r\n<p>Mas \u00e9? \u00c9 uma prote\u00edna rica em enxofre que se encontra naturalmente nos nossos cabelos. \u00c9 respons\u00e1vel por endurecer a camada superficial dos cabelos, nutrindo-os e reparando-os. Por isso, \u00e9 t\u00e3o importante manter os n\u00edveis dessa prote\u00edna em nossos cabelos. E \u00e9 aqui que os produtos de Queratina entram em a\u00e7\u00e3o. Dizemos quais s\u00e3o os nossos favoritos!<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Tudo sobre a Linha Agrado Cosmetic Queratina<\/h2>\r\n\r\n\r\n\r\n<p>A combina\u00e7\u00e3o de sol, sal e cloro pode danificar o cabelo e deix\u00e1-lo seco, opaco e quebradi\u00e7o. E ningu\u00e9m quer isso! Por isso, apresentamos a voc\u00ea o <a href=\"http:\/\/agradocosmetic.com\/pt\/linea\/keratina\/\" target=\"_blank\" rel=\"noreferrer noopener\">Linha Queratina da Agrado Cosmetic<\/a> que ser\u00e1 o seu melhor aliado durante os meses de ver\u00e3o. Com seus produtos desenvolvidos especificamente para proteger e reparar os cabelos, mant\u00ea-los macios, hidratados e com brilho radiante em qualquer esta\u00e7\u00e3o do ano.<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><a href=\"\/pt\/?p=583\" target=\"_blank\" rel=\"noreferrer noopener\">Champ\u00f4 Profissional Queratina<\/a>. Desde a primeira lavagem repara a cut\u00edcula da fibra, conferindo aos cabelos a maciez e vitalidade que os fatores externos danificaram. Um b\u00e1sico na sua rotina capilar!<\/li>\r\n\r\n\r\n\r\n<li><a href=\"\/pt\/?p=698\" target=\"_blank\" rel=\"noreferrer noopener\">Creme Suavizante Condicionador de Queratina<\/a>. Indicado para cabelos crespos, permite penteado f\u00e1cil e proporciona brilho intenso. Suavidade instant\u00e2nea!<\/li>\r\n\r\n\r\n\r\n<li><a href=\"\/pt\/?p=707\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1scara Capilar Queratina<\/a>. Sem d\u00favida o &#039;must have&#039; que consegue, desde a primeira aplica\u00e7\u00e3o, amaciar, nutrir e reparar os cabelos danificados e crespos. Um dos nossos favoritos!<\/li>\r\n\r\n\r\n\r\n<li><a href=\"\/pt\/?p=728\" target=\"_blank\" rel=\"noreferrer noopener\">Queratina L\u00edquida<\/a>. O produto que complementa o tratamento di\u00e1rio dos cabelos crespos. Incorpore-o na sua rotina de cuidados com os cabelos, junto com os produtos anteriores, para conseguir cabelos perfeitos. Juba de 10!<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p>Agora que voc\u00ea j\u00e1 conhece todas as dicas para exibir cabelos longos onde quer que v\u00e1, mime seus cabelos com o <a href=\"https:\/\/agradocosmetic.com\/pt\/linea\/keratina\/\" target=\"_blank\" rel=\"noreferrer noopener\">Linha Queratina<\/a>! Com <a href=\"https:\/\/agradocosmetic.com\/pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agrado Cosm\u00e9ticos<\/a> Voc\u00ea tem isso mais f\u00e1cil do que nunca. \ud83d\ude09<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1El verano est\u00e1 a la vuelta de la esquina! Un a\u00f1o m\u00e1s, vuelven d\u00edas de intenso calor, piscina, playa y sol. Y aunque estos planes nos apetecen mucho, tenemos que preparar nuestro pelo para que no sufra de m\u00e1s. Si a\u00fan no sabes c\u00f3mo, don\u2019t be panic, porque en Agrado Cosmetic te ense\u00f1amos la mejor [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":21231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[509,1],"tags":[561,569,563,571,567],"class_list":["post-20773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capilar-en","category-todos","tag-agrado-en","tag-cabello-en","tag-capilar-en","tag-linea-keratina-en","tag-pelo-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado<\/title>\n<meta name=\"description\" content=\"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don&#039;t be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado\" \/>\n<meta property=\"og:description\" content=\"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don&#039;t be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-08T10:58:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-18T16:58:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"agradocosmetic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"agradocosmetic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/\"},\"author\":{\"name\":\"agradocosmetic\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/person\\\/732e8d396022e25f9340196f83d6789d\"},\"headline\":\"Prepara tu pelo para el verano con la L\u00ednea Keratina\",\"datePublished\":\"2023-05-08T10:58:11+00:00\",\"dateModified\":\"2023-11-18T16:58:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/\"},\"wordCount\":430,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/mascarilla-agrado.jpg\",\"keywords\":[\"agrado\",\"cabello\",\"capilar\",\"l\u00ednea keratina\",\"pelo\"],\"articleSection\":[\"Capilar\",\"Todos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/\",\"name\":\"Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/mascarilla-agrado.jpg\",\"datePublished\":\"2023-05-08T10:58:11+00:00\",\"dateModified\":\"2023-11-18T16:58:46+00:00\",\"description\":\"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don't be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/mascarilla-agrado.jpg\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/mascarilla-agrado.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prepara tu pelo para el verano con la L\u00ednea Keratina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/person\\\/732e8d396022e25f9340196f83d6789d\",\"name\":\"agradocosmetic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g\",\"caption\":\"agradocosmetic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado","description":"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don't be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/","og_locale":"pt_PT","og_type":"article","og_title":"Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado","og_description":"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don't be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.","og_url":"https:\/\/agradocosmetic.com\/pt\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/","og_site_name":"Agrado","article_published_time":"2023-05-08T10:58:11+00:00","article_modified_time":"2023-11-18T16:58:46+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg","type":"image\/jpeg"}],"author":"agradocosmetic","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"agradocosmetic","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#article","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/"},"author":{"name":"agradocosmetic","@id":"https:\/\/agradocosmetic.com\/#\/schema\/person\/732e8d396022e25f9340196f83d6789d"},"headline":"Prepara tu pelo para el verano con la L\u00ednea Keratina","datePublished":"2023-05-08T10:58:11+00:00","dateModified":"2023-11-18T16:58:46+00:00","mainEntityOfPage":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/"},"wordCount":430,"commentCount":0,"publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"image":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg","keywords":["agrado","cabello","capilar","l\u00ednea keratina","pelo"],"articleSection":["Capilar","Todos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/","url":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/","name":"Prepara tu pelo para el verano con la L\u00ednea Keratina - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg","datePublished":"2023-05-08T10:58:11+00:00","dateModified":"2023-11-18T16:58:46+00:00","description":"Con el verano y todos sus factores da\u00f1inos, \u00a1Necesitas proteger tu pelo! Don't be panic porque te traemos la soluci\u00f3n: la L\u00ednea Keratina.","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/05\/mascarilla-agrado.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/prepara-tu-pelo-para-el-verano-con-la-linea-keratina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Prepara tu pelo para el verano con la L\u00ednea Keratina"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/agradocosmetic.com\/#\/schema\/person\/732e8d396022e25f9340196f83d6789d","name":"agradocosm\u00e9tico","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6003e45301182b7e125463fcbec403b1980909c12edf09098526b9a15e779c0?s=96&d=mm&r=g","caption":"agradocosmetic"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/20773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/comments?post=20773"}],"version-history":[{"count":1,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/20773\/revisions"}],"predecessor-version":[{"id":21232,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/posts\/20773\/revisions\/21232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/21231"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=20773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categories?post=20773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/tags?post=20773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}