{"id":22726,"date":"2023-10-26T09:58:50","date_gmt":"2023-10-26T09:58:50","guid":{"rendered":"https:\/\/dev-freelancerweb.site\/?post_type=producto&#038;p=22726"},"modified":"2026-09-01T14:21:37","modified_gmt":"2026-09-01T13:21:37","slug":"champu-profesional-reparador-nutritivo","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/pt\/producto\/champu-profesional-reparador-nutritivo\/","title":{"rendered":"Champ\u00f4 Profissional Reparador Nutritivo"},"content":{"rendered":"<p>O champ\u00f4 Reparador Nutritivo da AGRADO \u00e9 formulado com g\u00e9rmen de trigo, provitamina B5 e queratina. \u00c9 especialmente indicado para cabelos secos, danificados ou quebradi\u00e7os que necessitam de um fornecimento extra de hidrata\u00e7\u00e3o. A prote\u00edna de trigo, hidrata a raiz, dando brilho e vitalidade ao cabelo. O seu contributo de queratina aumenta a resist\u00eancia \u00e0 quebra e fortalece o cabelo. Dermatologicamente testado.<\/p>","protected":false},"featured_media":32184,"template":"","categoria-de-producto":[837,73,74,466],"class_list":["post-22726","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-400ml","categoria-de-producto-cuidado-capilar","categoria-de-producto-champu","categoria-de-producto-cabellos-danados-y-secos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Champ\u00fa Profesional Reparador Nutritivo - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/producto\/champu-profesional-reparador-nutritivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Champ\u00fa Profesional Reparador Nutritivo - Agrado\" \/>\n<meta property=\"og:description\" content=\"El champ\u00fa profesional Reparador Nutritivo AGRADO est\u00e1 especialmente indicado para cabellos muy secos y da\u00f1ados que necesitan un aporte extra de hidrataci\u00f3n. La prote\u00edna de trigo hidrata la ra\u00edz, aport\u00e1ndole brillo y vitalidad al cabello. Su aporte de keratina aumenta la resistencia a la rotura y lo fortalece. Dermatol\u00f3gicamente testado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/producto\/champu-profesional-reparador-nutritivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/10\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/\",\"name\":\"Champ\u00fa Profesional Reparador Nutritivo - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp\",\"datePublished\":\"2023-10-26T09:58:50+00:00\",\"dateModified\":\"2026-09-01T13:21:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp\",\"width\":800,\"height\":800,\"caption\":\"Champ\u00fa nutritivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/champu-profesional-reparador-nutritivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Champ\u00fa Profesional Reparador Nutritivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shampoo Reparador Nutritivo Profissional - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/producto\/champu-profesional-reparador-nutritivo\/","og_locale":"pt_PT","og_type":"article","og_title":"Champ\u00fa Profesional Reparador Nutritivo - Agrado","og_description":"El champ\u00fa profesional Reparador Nutritivo AGRADO est\u00e1 especialmente indicado para cabellos muy secos y da\u00f1ados que necesitan un aporte extra de hidrataci\u00f3n. La prote\u00edna de trigo hidrata la ra\u00edz, aport\u00e1ndole brillo y vitalidad al cabello. Su aporte de keratina aumenta la resistencia a la rotura y lo fortalece. Dermatol\u00f3gicamente testado.","og_url":"https:\/\/agradocosmetic.com\/pt\/producto\/champu-profesional-reparador-nutritivo\/","og_site_name":"Agrado","article_modified_time":"2026-09-01T13:21:37+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/10\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/","url":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/","name":"Shampoo Reparador Nutritivo Profissional - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/10\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp","datePublished":"2023-10-26T09:58:50+00:00","dateModified":"2026-09-01T13:21:37+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/10\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/10\/30005164-CHAMPU-NUTRI-REPARA-400ML.webp","width":800,"height":800,"caption":"Champ\u00fa nutritivo"},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/champu-profesional-reparador-nutritivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Champ\u00fa Profesional Reparador Nutritivo"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto\/22726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/32184"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=22726"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto?post=22726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}