{"id":29360,"date":"2025-01-09T11:53:27","date_gmt":"2025-01-09T10:53:27","guid":{"rendered":"https:\/\/agradocosmetic.com\/?post_type=producto&#038;p=29360"},"modified":"2026-07-09T15:24:13","modified_gmt":"2026-07-09T14:24:13","slug":"crema-de-manos-aloe-vera","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/pt\/producto\/crema-de-manos-aloe-vera\/","title":{"rendered":"Creme de M\u00e3os Alo\u00e9 Vera"},"content":{"rendered":"<p class=\"translation-block\">Cuidado essencial para suas m\u00e3os. Hidrata\u00e7\u00e3o e prote\u00e7\u00e3o.<br> F\u00f3rmula vegana com 95% ingredientes de origem natural.<br> Testado dermatologicamente.<\/p>","protected":false},"featured_media":29361,"template":"","categoria-de-producto":[103,104],"class_list":["post-29360","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-cuidado-de-manos","categoria-de-producto-crema"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crema de Manos Aloe Vera - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/producto\/crema-de-manos-aloe-vera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crema de Manos Aloe Vera - Agrado\" \/>\n<meta property=\"og:description\" content=\"Cuidado esencial para tus manos. Hidrataci\u00f3n y protecci\u00f3n. F\u00f3rmula vegana y con 95% ingredientes de origen natural. Testado dermatol\u00f3gicamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/producto\/crema-de-manos-aloe-vera\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T14:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/01\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/\",\"name\":\"Crema de Manos Aloe Vera - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp\",\"datePublished\":\"2025-01-09T10:53:27+00:00\",\"dateModified\":\"2026-07-09T14:24:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/crema-de-manos-aloe-vera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crema de Manos Aloe Vera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creme para as M\u00e3os de Aloe Vera - Prazer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/producto\/crema-de-manos-aloe-vera\/","og_locale":"pt_PT","og_type":"article","og_title":"Crema de Manos Aloe Vera - Agrado","og_description":"Cuidado esencial para tus manos. Hidrataci\u00f3n y protecci\u00f3n. F\u00f3rmula vegana y con 95% ingredientes de origen natural. Testado dermatol\u00f3gicamente.","og_url":"https:\/\/agradocosmetic.com\/pt\/producto\/crema-de-manos-aloe-vera\/","og_site_name":"Agrado","article_modified_time":"2026-07-09T14:24:13+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/01\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/","url":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/","name":"Creme para as M\u00e3os de Aloe Vera - Prazer","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/01\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp","datePublished":"2025-01-09T10:53:27+00:00","dateModified":"2026-07-09T14:24:13+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/01\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2025\/01\/30009680-AGRADO-CR-MANOS-ALOE-75ML-2.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/crema-de-manos-aloe-vera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Crema de Manos Aloe Vera"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto\/29360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/29361"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=29360"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto?post=29360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}