{"id":421,"date":"2023-08-18T22:45:30","date_gmt":"2023-08-18T22:45:30","guid":{"rendered":"https:\/\/dev-freelancerweb.site\/?post_type=producto&#038;p=421"},"modified":"2024-04-26T09:09:02","modified_gmt":"2024-04-26T09:09:02","slug":"gel-bano-ducha-leche-coco","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-bano-ducha-leche-coco\/","title":{"rendered":"Gel de Duche Leite de Coco"},"content":{"rendered":"<p>O Gel e Duche Leite de Coco da AGRADO \u00e9 formulado para cuidar, limpar e suavizar a pele. Com aroma suave a coco que ir\u00e1 cativ\u00e1-lo. Adequado para o uso di\u00e1rio em todo o tipo de peles gra\u00e7as ao pH neutro da sua f\u00f3rmula. Dermatologicamente testado. F\u00d3RMULA MELHORADA.<\/p>","protected":false},"featured_media":26783,"template":"","categoria-de-producto":[81,82,84],"class_list":["post-421","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-cuidado-corporal","categoria-de-producto-gel-de-bano","categoria-de-producto-nutritivas-y-frutales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gel de Ducha Leche De Coco - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/producto\/gel-bano-ducha-leche-coco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gel de Ducha Leche De Coco - Agrado\" \/>\n<meta property=\"og:description\" content=\"El Gel de ducha Leche de Coco AGRADO est\u00e1 formuladopara cuidar, limpiar y suavizar la piel. Con suave aroma a coco que te cautivar\u00e1. Apto para su uso diario en todo tipo de pieles gracias al pH neutro de su f\u00f3rmula. Dermatol\u00f3gicamente testado. F\u00d3RMULA MEJORADA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/producto\/gel-bano-ducha-leche-coco\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T09:09:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30005966-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/\",\"name\":\"Gel de Ducha Leche De Coco - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30005966-1.png\",\"datePublished\":\"2023-08-18T22:45:30+00:00\",\"dateModified\":\"2024-04-26T09:09:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30005966-1.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30005966-1.png\",\"width\":799,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-bano-ducha-leche-coco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gel de Ducha Leche De Coco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gel de banho com leite de coco - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-bano-ducha-leche-coco\/","og_locale":"pt_PT","og_type":"article","og_title":"Gel de Ducha Leche De Coco - Agrado","og_description":"El Gel de ducha Leche de Coco AGRADO est\u00e1 formuladopara cuidar, limpiar y suavizar la piel. Con suave aroma a coco que te cautivar\u00e1. Apto para su uso diario en todo tipo de pieles gracias al pH neutro de su f\u00f3rmula. Dermatol\u00f3gicamente testado. F\u00d3RMULA MEJORADA.","og_url":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-bano-ducha-leche-coco\/","og_site_name":"Agrado","article_modified_time":"2024-04-26T09:09:02+00:00","og_image":[{"width":799,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30005966-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/","url":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/","name":"Gel de banho com leite de coco - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30005966-1.png","datePublished":"2023-08-18T22:45:30+00:00","dateModified":"2024-04-26T09:09:02+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30005966-1.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30005966-1.png","width":799,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/gel-bano-ducha-leche-coco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Gel de Ducha Leche De Coco"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/26783"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=421"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto?post=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}