{"id":439,"date":"2023-08-19T20:28:41","date_gmt":"2023-08-19T20:28:41","guid":{"rendered":"https:\/\/dev-freelancerweb.site\/?post_type=producto&#038;p=439"},"modified":"2024-04-26T09:06:37","modified_gmt":"2024-04-26T09:06:37","slug":"gel-de-bano-y-ducha-mediterraneo","status":"publish","type":"producto","link":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-de-bano-y-ducha-mediterraneo\/","title":{"rendered":"Gel De Duche Mediterr\u00e2neo"},"content":{"rendered":"<p>A linha G\u00c9IS DO MUNDO da AGRADO \u00e9 composta por produtos concebidos para transportar para o duche as sensa\u00e7\u00f5es de uma viagem \u00e0 volta do mundo e criar uma experi\u00eancia \u00fanica. N\u00e3o \u00e9 poss\u00edvel conceber uma volta ao mundo sem uma paragem no ber\u00e7o das culturas: o Mediterr\u00e2neo. Os seus aromas c\u00edtricos rodeiam-nos enquanto desfrutamos de toda a magia das suas tradi\u00e7\u00f5es entre campo e mar e a sabedoria das suas gentes. Dermatologicamente testado.<\/p>","protected":false},"featured_media":26796,"template":"","categoria-de-producto":[81,82,85],"class_list":["post-439","producto","type-producto","status-publish","has-post-thumbnail","hentry","categoria-de-producto-cuidado-corporal","categoria-de-producto-gel-de-bano","categoria-de-producto-aromaticas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gel de Ducha Mediterr\u00e1neo - Agrado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agradocosmetic.com\/pt\/producto\/gel-de-bano-y-ducha-mediterraneo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gel de Ducha Mediterr\u00e1neo - Agrado\" \/>\n<meta property=\"og:description\" content=\"La l\u00ednea GELES DEL MUNDO de AGRADO, est\u00e1 compuesta por productos dise\u00f1ados para transportar las sensaciones de viajar alrededor del mundo hasta tu ducha y crear una experiencia \u00fanica. Una vuelta al mundo no se concibe sin una parada en la cuna de las culturas: el Mediterr\u00e1neo. Sus aromas c\u00edtricos nos rodean mientras disfrutamos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agradocosmetic.com\/pt\/producto\/gel-de-bano-y-ducha-mediterraneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Agrado\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T09:06:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30006177.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/\",\"name\":\"Gel de Ducha Mediterr\u00e1neo - Agrado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30006177.png\",\"datePublished\":\"2023-08-19T20:28:41+00:00\",\"dateModified\":\"2024-04-26T09:06:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30006177.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/30006177.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/producto\\\/gel-de-bano-y-ducha-mediterraneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/agradocosmetic.com\\\/pt\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gel de Ducha Mediterr\u00e1neo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#website\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"name\":\"Agrado\",\"description\":\"Cosmetic\",\"publisher\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agradocosmetic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#organization\",\"name\":\"Agrado\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"contentUrl\":\"https:\\\/\\\/agradocosmetic.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/LOGO-AGRADO-WEB-01.png\",\"width\":1632,\"height\":300,\"caption\":\"Agrado\"},\"image\":{\"@id\":\"https:\\\/\\\/agradocosmetic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gel de Banho Mediterr\u00e2neo - Agrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-de-bano-y-ducha-mediterraneo\/","og_locale":"pt_PT","og_type":"article","og_title":"Gel de Ducha Mediterr\u00e1neo - Agrado","og_description":"La l\u00ednea GELES DEL MUNDO de AGRADO, est\u00e1 compuesta por productos dise\u00f1ados para transportar las sensaciones de viajar alrededor del mundo hasta tu ducha y crear una experiencia \u00fanica. Una vuelta al mundo no se concibe sin una parada en la cuna de las culturas: el Mediterr\u00e1neo. Sus aromas c\u00edtricos nos rodean mientras disfrutamos de [&hellip;]","og_url":"https:\/\/agradocosmetic.com\/pt\/producto\/gel-de-bano-y-ducha-mediterraneo\/","og_site_name":"Agrado","article_modified_time":"2024-04-26T09:06:37+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30006177.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/","url":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/","name":"Gel de Banho Mediterr\u00e2neo - Agrado","isPartOf":{"@id":"https:\/\/agradocosmetic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/#primaryimage"},"image":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/#primaryimage"},"thumbnailUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30006177.png","datePublished":"2023-08-19T20:28:41+00:00","dateModified":"2024-04-26T09:06:37+00:00","breadcrumb":{"@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/#primaryimage","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30006177.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/08\/30006177.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agradocosmetic.com\/producto\/gel-de-bano-y-ducha-mediterraneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agradocosmetic.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/agradocosmetic.com\/pt\/producto\/"},{"@type":"ListItem","position":3,"name":"Gel de Ducha Mediterr\u00e1neo"}]},{"@type":"WebSite","@id":"https:\/\/agradocosmetic.com\/#website","url":"https:\/\/agradocosmetic.com\/","name":"Gosto","description":"Cosm\u00e9tico","publisher":{"@id":"https:\/\/agradocosmetic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agradocosmetic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/agradocosmetic.com\/#organization","name":"Gosto","url":"https:\/\/agradocosmetic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/","url":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","contentUrl":"https:\/\/agradocosmetic.com\/wp-content\/uploads\/2023\/07\/LOGO-AGRADO-WEB-01.png","width":1632,"height":300,"caption":"Agrado"},"image":{"@id":"https:\/\/agradocosmetic.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media\/26796"}],"wp:attachment":[{"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"categoria-de-producto","embeddable":true,"href":"https:\/\/agradocosmetic.com\/pt\/wp-json\/wp\/v2\/categoria-de-producto?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}